{"id":11,"count":15,"description":"","link":"https:\/\/riyagroup.travel\/blog\/index.php\/category\/holidays\/","name":"Holidays","slug":"holidays","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\r\n<title>Holidays Archives - Blog<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/riyagroup.travel\/blog\/index.php\/category\/holidays\/\" \/>\r\n<meta property=\"og:locale\" content=\"en_US\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Holidays Archives - Blog\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/riyagroup.travel\/blog\/index.php\/category\/holidays\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Blog\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/riyagroup.travel\/blog\/index.php\/category\/holidays\/\",\"url\":\"https:\/\/riyagroup.travel\/blog\/index.php\/category\/holidays\/\",\"name\":\"Holidays Archives - Blog\",\"isPartOf\":{\"@id\":\"https:\/\/riyagroup.travel\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/riyagroup.travel\/blog\/index.php\/category\/holidays\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/riyagroup.travel\/blog\/index.php\/category\/holidays\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/riyagroup.travel\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Holidays\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/riyagroup.travel\/blog\/#website\",\"url\":\"https:\/\/riyagroup.travel\/blog\/\",\"name\":\"Blog\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/riyagroup.travel\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Holidays Archives - Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/riyagroup.travel\/blog\/index.php\/category\/holidays\/","og_locale":"en_US","og_type":"article","og_title":"Holidays Archives - Blog","og_url":"https:\/\/riyagroup.travel\/blog\/index.php\/category\/holidays\/","og_site_name":"Blog","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/riyagroup.travel\/blog\/index.php\/category\/holidays\/","url":"https:\/\/riyagroup.travel\/blog\/index.php\/category\/holidays\/","name":"Holidays Archives - Blog","isPartOf":{"@id":"https:\/\/riyagroup.travel\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/riyagroup.travel\/blog\/index.php\/category\/holidays\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/riyagroup.travel\/blog\/index.php\/category\/holidays\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/riyagroup.travel\/blog\/"},{"@type":"ListItem","position":2,"name":"Holidays"}]},{"@type":"WebSite","@id":"https:\/\/riyagroup.travel\/blog\/#website","url":"https:\/\/riyagroup.travel\/blog\/","name":"Blog","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/riyagroup.travel\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/riyagroup.travel\/blog\/index.php\/wp-json\/wp\/v2\/categories\/11"}],"collection":[{"href":"https:\/\/riyagroup.travel\/blog\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/riyagroup.travel\/blog\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/riyagroup.travel\/blog\/index.php\/wp-json\/wp\/v2\/posts?categories=11"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}